{"id":1276,"date":"2021-04-27T09:41:23","date_gmt":"2021-04-27T07:41:23","guid":{"rendered":"http:\/\/agilepolska.pl\/zwinnyblog\/?p=1276"},"modified":"2021-04-27T09:42:39","modified_gmt":"2021-04-27T07:42:39","slug":"konferencja-inzynierii-oprogramowania-beit-2","status":"publish","type":"post","link":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/","title":{"rendered":"Konferencja In\u017cynierii Oprogramowania beIT"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/agilepolska.pl\/zwinnyblog\/wp-content\/uploads\/2021\/04\/BeIT2021.jpg\" alt=\"\" class=\"wp-image-1277\" width=\"609\" height=\"365\" srcset=\"https:\/\/agilepolska.pl\/zwinnyblog\/wp-content\/uploads\/2021\/04\/BeIT2021.jpg 500w, https:\/\/agilepolska.pl\/zwinnyblog\/wp-content\/uploads\/2021\/04\/BeIT2021-300x180.jpg 300w\" sizes=\"auto, (max-width: 609px) 100vw, 609px\" \/><\/figure><\/div>\n\n\n\n<p>Zapraszamy na <a rel=\"noreferrer noopener\" aria-label=\"Konferencj\u0119 In\u017cynierii Oprogramowania beIT (otwiera si\u0119 na nowej zak\u0142adce)\" href=\"https:\/\/www.facebook.com\/events\/3418921208208942\" target=\"_blank\">Konferencj\u0119 In\u017cynierii Oprogramowania beIT<\/a>.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>W tym roku wydarzenie odb\u0119dzie si\u0119 w 100% online. W dwa weekendy od 22 do 23 maja oraz od 29 do 30 maja 2021 odb\u0119d\u0105 si\u0119 wyk\u0142ady i warsztaty z 7 r\u00f3\u017cnych \u015bcie\u017cek tematycznych.\u00a0B\u0119d\u0105 one dotyczy\u0107 zagadnie\u0144 zwi\u0105zanych przede wszystkim ze sztuczn\u0105 inteligencj\u0105, testowaniem oprogramowania, metodykami zwinnymi, analiz\u0105 biznesow\u0105 i kszta\u0142towaniem umiej\u0119tno\u015bci przyw\u00f3dczych w bran\u017cy IT. <\/p>\n\n\n\n<p>Wyk\u0142ady otwieraj\u0105ce i zamykaj\u0105ce wydarzenie poprowadz\u0105 dla Was do\u015bwiadczeni w bran\u017cy prelegenci &#8211; Sebastian Wilczewski, kt\u00f3ry, z praktycznego punkty widzenia, opowie Wam o zwinnym zarz\u0105dzaniu projektami w \u015bwiecie VUCA i Piotr Nowosielski, kt\u00f3ry podczas prelekcji odpowie na pytanie: \u201cDlaczego najlepsze rzeczy w marketingu s\u0105 za darmo?\u201d\u00a0<\/p>\n\n\n\n<p>Udzia\u0142 w wyk\u0142adach jest darmowy, natomiast chc\u0105c uczestniczy\u0107 w warsztatach, uczestnicy zobowi\u0105zani s\u0105 do zakupu bilet\u00f3w na wybrane przez siebie \u015bcie\u017cki tematyczne.\u00a0<\/p>\n\n\n\n<p>Wi\u0119cej szczeg\u00f3\u0142\u00f3w: <a href=\"https:\/\/www.facebook.com\/events\/3418921208208942\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"https:\/\/www.facebook.com\/events\/3418921208208942 (otwiera si\u0119 na nowej zak\u0142adce)\">https:\/\/www.facebook.com\/events\/3418921208208942<\/a><\/p>\n\n\n\n<p>Harmonogram i link do zapis\u00f3w (wyk\u0142ady):\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/forms.gle\/rwmXskdJPAtGDYmf7?fbclid=IwAR1s4BEad9FETYFP6tg8yeyHf5nrrN4FIPTmFct--LYQ7TQk8CxeB399g9k\" target=\"_blank\">https:\/\/forms.gle\/rwmXskdJPAtGDYmf7<\/a><\/p>\n\n\n\n<p>Harmonogram i link do zapis\u00f3w (warsztaty): <a rel=\"noreferrer noopener\" href=\"https:\/\/evenea.pl\/pl\/wydarzenie\/KonferencjabeIT2021?fbclid=IwAR2dpsI3rnC9CtbZ2QSya4F3ARb4-lud2dHLFoheVb917LJaylu7f0ZY7a0\" target=\"_blank\">https:\/\/evenea.pl\/pl\/wydarzenie\/KonferencjabeIT2021<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zapraszamy na Konferencj\u0119 In\u017cynierii Oprogramowania beIT.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[37,38],"tags":[],"class_list":["post-1276","post","type-post","status-publish","format-standard","hentry","category-konferencje","category-newsy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Konferencja In\u017cynierii Oprogramowania beIT - Agile Polska<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Konferencja In\u017cynierii Oprogramowania beIT - Agile Polska\" \/>\n<meta property=\"og:description\" content=\"Zapraszamy na Konferencj\u0119 In\u017cynierii Oprogramowania beIT.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Agile Polska\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-27T07:41:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T07:42:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/agilepolska.pl\/zwinnyblog\/wp-content\/uploads\/2021\/04\/BeIT2021.jpg\" \/>\n<meta name=\"author\" content=\"Opublikowane przez Ma\u0142gorzata Zelek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Opublikowane przez Ma\u0142gorzata Zelek\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/\"},\"author\":{\"name\":\"Opublikowane przez Ma\u0142gorzata Zelek\",\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/#\\\/schema\\\/person\\\/248b4dfd24a6328190a8805895a3c098\"},\"headline\":\"Konferencja In\u017cynierii Oprogramowania beIT\",\"datePublished\":\"2021-04-27T07:41:23+00:00\",\"dateModified\":\"2021-04-27T07:42:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/\"},\"wordCount\":189,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/BeIT2021.jpg\",\"articleSection\":[\"Konferencje\",\"Newsy\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/\",\"url\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/\",\"name\":\"Konferencja In\u017cynierii Oprogramowania beIT - Agile Polska\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/BeIT2021.jpg\",\"datePublished\":\"2021-04-27T07:41:23+00:00\",\"dateModified\":\"2021-04-27T07:42:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/#\\\/schema\\\/person\\\/248b4dfd24a6328190a8805895a3c098\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/BeIT2021.jpg\",\"contentUrl\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/BeIT2021.jpg\",\"width\":500,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/2021\\\/04\\\/27\\\/konferencja-inzynierii-oprogramowania-beit-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Konferencja In\u017cynierii Oprogramowania beIT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/#website\",\"url\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/\",\"name\":\"Agile Polska\",\"description\":\"#zwinnyprzewodnik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/#\\\/schema\\\/person\\\/248b4dfd24a6328190a8805895a3c098\",\"name\":\"Opublikowane przez Ma\u0142gorzata Zelek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb4e1e62460a20ae105aa996065b23e07692f0e793f3e1de14553cbc18a11f3b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb4e1e62460a20ae105aa996065b23e07692f0e793f3e1de14553cbc18a11f3b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb4e1e62460a20ae105aa996065b23e07692f0e793f3e1de14553cbc18a11f3b?s=96&d=mm&r=g\",\"caption\":\"Opublikowane przez Ma\u0142gorzata Zelek\"},\"url\":\"https:\\\/\\\/agilepolska.pl\\\/zwinnyblog\\\/author\\\/malgorzata-zeleksube-pl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Konferencja In\u017cynierii Oprogramowania beIT - Agile Polska","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/","og_locale":"pl_PL","og_type":"article","og_title":"Konferencja In\u017cynierii Oprogramowania beIT - Agile Polska","og_description":"Zapraszamy na Konferencj\u0119 In\u017cynierii Oprogramowania beIT.","og_url":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/","og_site_name":"Agile Polska","article_published_time":"2021-04-27T07:41:23+00:00","article_modified_time":"2021-04-27T07:42:39+00:00","og_image":[{"url":"http:\/\/agilepolska.pl\/zwinnyblog\/wp-content\/uploads\/2021\/04\/BeIT2021.jpg","type":"","width":"","height":""}],"author":"Opublikowane przez Ma\u0142gorzata Zelek","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Opublikowane przez Ma\u0142gorzata Zelek","Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/#article","isPartOf":{"@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/"},"author":{"name":"Opublikowane przez Ma\u0142gorzata Zelek","@id":"https:\/\/agilepolska.pl\/zwinnyblog\/#\/schema\/person\/248b4dfd24a6328190a8805895a3c098"},"headline":"Konferencja In\u017cynierii Oprogramowania beIT","datePublished":"2021-04-27T07:41:23+00:00","dateModified":"2021-04-27T07:42:39+00:00","mainEntityOfPage":{"@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/"},"wordCount":189,"commentCount":0,"image":{"@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/#primaryimage"},"thumbnailUrl":"http:\/\/agilepolska.pl\/zwinnyblog\/wp-content\/uploads\/2021\/04\/BeIT2021.jpg","articleSection":["Konferencje","Newsy"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/","url":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/","name":"Konferencja In\u017cynierii Oprogramowania beIT - Agile Polska","isPartOf":{"@id":"https:\/\/agilepolska.pl\/zwinnyblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/#primaryimage"},"image":{"@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/#primaryimage"},"thumbnailUrl":"http:\/\/agilepolska.pl\/zwinnyblog\/wp-content\/uploads\/2021\/04\/BeIT2021.jpg","datePublished":"2021-04-27T07:41:23+00:00","dateModified":"2021-04-27T07:42:39+00:00","author":{"@id":"https:\/\/agilepolska.pl\/zwinnyblog\/#\/schema\/person\/248b4dfd24a6328190a8805895a3c098"},"breadcrumb":{"@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/#primaryimage","url":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-content\/uploads\/2021\/04\/BeIT2021.jpg","contentUrl":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-content\/uploads\/2021\/04\/BeIT2021.jpg","width":500,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/agilepolska.pl\/zwinnyblog\/2021\/04\/27\/konferencja-inzynierii-oprogramowania-beit-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/agilepolska.pl\/zwinnyblog\/"},{"@type":"ListItem","position":2,"name":"Konferencja In\u017cynierii Oprogramowania beIT"}]},{"@type":"WebSite","@id":"https:\/\/agilepolska.pl\/zwinnyblog\/#website","url":"https:\/\/agilepolska.pl\/zwinnyblog\/","name":"Agile Polska","description":"#zwinnyprzewodnik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agilepolska.pl\/zwinnyblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Person","@id":"https:\/\/agilepolska.pl\/zwinnyblog\/#\/schema\/person\/248b4dfd24a6328190a8805895a3c098","name":"Opublikowane przez Ma\u0142gorzata Zelek","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/secure.gravatar.com\/avatar\/bb4e1e62460a20ae105aa996065b23e07692f0e793f3e1de14553cbc18a11f3b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb4e1e62460a20ae105aa996065b23e07692f0e793f3e1de14553cbc18a11f3b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb4e1e62460a20ae105aa996065b23e07692f0e793f3e1de14553cbc18a11f3b?s=96&d=mm&r=g","caption":"Opublikowane przez Ma\u0142gorzata Zelek"},"url":"https:\/\/agilepolska.pl\/zwinnyblog\/author\/malgorzata-zeleksube-pl\/"}]}},"_links":{"self":[{"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/posts\/1276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/comments?post=1276"}],"version-history":[{"count":2,"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/posts\/1276\/revisions"}],"predecessor-version":[{"id":1279,"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/posts\/1276\/revisions\/1279"}],"wp:attachment":[{"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/media?parent=1276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/categories?post=1276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agilepolska.pl\/zwinnyblog\/wp-json\/wp\/v2\/tags?post=1276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}